{"id":4213,"date":"2019-06-17T11:43:00","date_gmt":"2019-06-16T23:43:00","guid":{"rendered":"https:\/\/hifihq.co.nz\/blog\/?p=4213"},"modified":"2022-06-19T11:47:34","modified_gmt":"2022-06-18T23:47:34","slug":"audio-physic-classic-8-lite-magazin-de-review","status":"publish","type":"post","link":"https:\/\/hifihq.co.nz\/blog\/audio-physic-classic-8-lite-magazin-de-review\/","title":{"rendered":"Audio Physic Classic 8 lite-magazin.de Review"},"content":{"rendered":"\n<p><\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><a href=\"https:\/\/hifihq.co.nz\/blog\/wp-content\/uploads\/2022\/06\/lite-magazine_review_CLASSIC8_PDF_web_en-1-scaled.jpg\" target=\"_blank\" rel=\"noreferrer noopener\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/hifihq.co.nz\/blog\/wp-content\/uploads\/2022\/06\/lite-magazine_review_CLASSIC8_PDF_web_en-1-750x1024.jpg\" alt=\"\" class=\"wp-image-4223\" width=\"839\" height=\"1146\" srcset=\"https:\/\/hifihq.co.nz\/blog\/wp-content\/uploads\/2022\/06\/lite-magazine_review_CLASSIC8_PDF_web_en-1-750x1024.jpg 750w, https:\/\/hifihq.co.nz\/blog\/wp-content\/uploads\/2022\/06\/lite-magazine_review_CLASSIC8_PDF_web_en-1-220x300.jpg 220w, https:\/\/hifihq.co.nz\/blog\/wp-content\/uploads\/2022\/06\/lite-magazine_review_CLASSIC8_PDF_web_en-1-768x1049.jpg 768w, https:\/\/hifihq.co.nz\/blog\/wp-content\/uploads\/2022\/06\/lite-magazine_review_CLASSIC8_PDF_web_en-1-1125x1536.jpg 1125w, https:\/\/hifihq.co.nz\/blog\/wp-content\/uploads\/2022\/06\/lite-magazine_review_CLASSIC8_PDF_web_en-1-1500x2048.jpg 1500w, https:\/\/hifihq.co.nz\/blog\/wp-content\/uploads\/2022\/06\/lite-magazine_review_CLASSIC8_PDF_web_en-1-scaled.jpg 1875w\" sizes=\"auto, (max-width: 839px) 100vw, 839px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><a href=\"https:\/\/hifihq.co.nz\/blog\/wp-content\/uploads\/2022\/06\/lite-magazine_review_CLASSIC8_PDF_web_en-2-scaled.jpg\" target=\"_blank\" rel=\"noreferrer noopener\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/hifihq.co.nz\/blog\/wp-content\/uploads\/2022\/06\/lite-magazine_review_CLASSIC8_PDF_web_en-2-773x1024.jpg\" alt=\"\" class=\"wp-image-4224\" width=\"842\" height=\"1115\" srcset=\"https:\/\/hifihq.co.nz\/blog\/wp-content\/uploads\/2022\/06\/lite-magazine_review_CLASSIC8_PDF_web_en-2-773x1024.jpg 773w, https:\/\/hifihq.co.nz\/blog\/wp-content\/uploads\/2022\/06\/lite-magazine_review_CLASSIC8_PDF_web_en-2-227x300.jpg 227w, https:\/\/hifihq.co.nz\/blog\/wp-content\/uploads\/2022\/06\/lite-magazine_review_CLASSIC8_PDF_web_en-2-768x1017.jpg 768w, https:\/\/hifihq.co.nz\/blog\/wp-content\/uploads\/2022\/06\/lite-magazine_review_CLASSIC8_PDF_web_en-2-1160x1536.jpg 1160w, https:\/\/hifihq.co.nz\/blog\/wp-content\/uploads\/2022\/06\/lite-magazine_review_CLASSIC8_PDF_web_en-2-1547x2048.jpg 1547w, https:\/\/hifihq.co.nz\/blog\/wp-content\/uploads\/2022\/06\/lite-magazine_review_CLASSIC8_PDF_web_en-2-scaled.jpg 1933w\" sizes=\"auto, (max-width: 842px) 100vw, 842px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><a href=\"https:\/\/hifihq.co.nz\/blog\/wp-content\/uploads\/2022\/06\/lite-magazine_review_CLASSIC8_PDF_web_en-3-scaled.jpg\" target=\"_blank\" rel=\"noreferrer noopener\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/hifihq.co.nz\/blog\/wp-content\/uploads\/2022\/06\/lite-magazine_review_CLASSIC8_PDF_web_en-3-704x1024.jpg\" alt=\"\" class=\"wp-image-4225\" width=\"840\" height=\"1222\" srcset=\"https:\/\/hifihq.co.nz\/blog\/wp-content\/uploads\/2022\/06\/lite-magazine_review_CLASSIC8_PDF_web_en-3-704x1024.jpg 704w, https:\/\/hifihq.co.nz\/blog\/wp-content\/uploads\/2022\/06\/lite-magazine_review_CLASSIC8_PDF_web_en-3-206x300.jpg 206w, https:\/\/hifihq.co.nz\/blog\/wp-content\/uploads\/2022\/06\/lite-magazine_review_CLASSIC8_PDF_web_en-3-768x1117.jpg 768w, https:\/\/hifihq.co.nz\/blog\/wp-content\/uploads\/2022\/06\/lite-magazine_review_CLASSIC8_PDF_web_en-3-1057x1536.jpg 1057w, https:\/\/hifihq.co.nz\/blog\/wp-content\/uploads\/2022\/06\/lite-magazine_review_CLASSIC8_PDF_web_en-3-1409x2048.jpg 1409w, https:\/\/hifihq.co.nz\/blog\/wp-content\/uploads\/2022\/06\/lite-magazine_review_CLASSIC8_PDF_web_en-3-scaled.jpg 1761w\" sizes=\"auto, (max-width: 840px) 100vw, 840px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><a href=\"https:\/\/hifihq.co.nz\/blog\/wp-content\/uploads\/2022\/06\/lite-magazine_review_CLASSIC8_PDF_web_en-4-scaled.jpg\" target=\"_blank\" rel=\"noreferrer noopener\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/hifihq.co.nz\/blog\/wp-content\/uploads\/2022\/06\/lite-magazine_review_CLASSIC8_PDF_web_en-4-769x1024.jpg\" alt=\"\" class=\"wp-image-4226\" width=\"839\" height=\"1117\" srcset=\"https:\/\/hifihq.co.nz\/blog\/wp-content\/uploads\/2022\/06\/lite-magazine_review_CLASSIC8_PDF_web_en-4-769x1024.jpg 769w, https:\/\/hifihq.co.nz\/blog\/wp-content\/uploads\/2022\/06\/lite-magazine_review_CLASSIC8_PDF_web_en-4-225x300.jpg 225w, https:\/\/hifihq.co.nz\/blog\/wp-content\/uploads\/2022\/06\/lite-magazine_review_CLASSIC8_PDF_web_en-4-768x1022.jpg 768w, https:\/\/hifihq.co.nz\/blog\/wp-content\/uploads\/2022\/06\/lite-magazine_review_CLASSIC8_PDF_web_en-4-1154x1536.jpg 1154w, https:\/\/hifihq.co.nz\/blog\/wp-content\/uploads\/2022\/06\/lite-magazine_review_CLASSIC8_PDF_web_en-4-1539x2048.jpg 1539w, https:\/\/hifihq.co.nz\/blog\/wp-content\/uploads\/2022\/06\/lite-magazine_review_CLASSIC8_PDF_web_en-4-scaled.jpg 1923w\" sizes=\"auto, (max-width: 839px) 100vw, 839px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><a href=\"https:\/\/hifihq.co.nz\/blog\/wp-content\/uploads\/2022\/06\/lite-magazine_review_CLASSIC8_PDF_web_en-5-scaled.jpg\" target=\"_blank\" rel=\"noreferrer noopener\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/hifihq.co.nz\/blog\/wp-content\/uploads\/2022\/06\/lite-magazine_review_CLASSIC8_PDF_web_en-5-761x1024.jpg\" alt=\"\" class=\"wp-image-4227\" width=\"841\" height=\"1132\" srcset=\"https:\/\/hifihq.co.nz\/blog\/wp-content\/uploads\/2022\/06\/lite-magazine_review_CLASSIC8_PDF_web_en-5-761x1024.jpg 761w, https:\/\/hifihq.co.nz\/blog\/wp-content\/uploads\/2022\/06\/lite-magazine_review_CLASSIC8_PDF_web_en-5-223x300.jpg 223w, https:\/\/hifihq.co.nz\/blog\/wp-content\/uploads\/2022\/06\/lite-magazine_review_CLASSIC8_PDF_web_en-5-768x1033.jpg 768w, https:\/\/hifihq.co.nz\/blog\/wp-content\/uploads\/2022\/06\/lite-magazine_review_CLASSIC8_PDF_web_en-5-1142x1536.jpg 1142w, https:\/\/hifihq.co.nz\/blog\/wp-content\/uploads\/2022\/06\/lite-magazine_review_CLASSIC8_PDF_web_en-5-1523x2048.jpg 1523w, https:\/\/hifihq.co.nz\/blog\/wp-content\/uploads\/2022\/06\/lite-magazine_review_CLASSIC8_PDF_web_en-5-scaled.jpg 1904w\" sizes=\"auto, (max-width: 841px) 100vw, 841px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><a href=\"https:\/\/hifihq.co.nz\/blog\/wp-content\/uploads\/2022\/06\/lite-magazine_review_CLASSIC8_PDF_web_en-6-scaled.jpg\" target=\"_blank\" rel=\"noreferrer noopener\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/hifihq.co.nz\/blog\/wp-content\/uploads\/2022\/06\/lite-magazine_review_CLASSIC8_PDF_web_en-6-770x1024.jpg\" alt=\"\" class=\"wp-image-4228\" width=\"841\" height=\"1118\" srcset=\"https:\/\/hifihq.co.nz\/blog\/wp-content\/uploads\/2022\/06\/lite-magazine_review_CLASSIC8_PDF_web_en-6-770x1024.jpg 770w, https:\/\/hifihq.co.nz\/blog\/wp-content\/uploads\/2022\/06\/lite-magazine_review_CLASSIC8_PDF_web_en-6-226x300.jpg 226w, https:\/\/hifihq.co.nz\/blog\/wp-content\/uploads\/2022\/06\/lite-magazine_review_CLASSIC8_PDF_web_en-6-768x1021.jpg 768w, https:\/\/hifihq.co.nz\/blog\/wp-content\/uploads\/2022\/06\/lite-magazine_review_CLASSIC8_PDF_web_en-6-1155x1536.jpg 1155w, https:\/\/hifihq.co.nz\/blog\/wp-content\/uploads\/2022\/06\/lite-magazine_review_CLASSIC8_PDF_web_en-6-1540x2048.jpg 1540w, https:\/\/hifihq.co.nz\/blog\/wp-content\/uploads\/2022\/06\/lite-magazine_review_CLASSIC8_PDF_web_en-6-scaled.jpg 1925w\" sizes=\"auto, (max-width: 841px) 100vw, 841px\" \/><\/a><\/figure>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[6],"tags":[],"class_list":["post-4213","post","type-post","status-publish","format-standard","hentry","category-reviews"],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/hifihq.co.nz\/blog\/wp-json\/wp\/v2\/posts\/4213","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hifihq.co.nz\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hifihq.co.nz\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hifihq.co.nz\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/hifihq.co.nz\/blog\/wp-json\/wp\/v2\/comments?post=4213"}],"version-history":[{"count":2,"href":"https:\/\/hifihq.co.nz\/blog\/wp-json\/wp\/v2\/posts\/4213\/revisions"}],"predecessor-version":[{"id":4229,"href":"https:\/\/hifihq.co.nz\/blog\/wp-json\/wp\/v2\/posts\/4213\/revisions\/4229"}],"wp:attachment":[{"href":"https:\/\/hifihq.co.nz\/blog\/wp-json\/wp\/v2\/media?parent=4213"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hifihq.co.nz\/blog\/wp-json\/wp\/v2\/categories?post=4213"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hifihq.co.nz\/blog\/wp-json\/wp\/v2\/tags?post=4213"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}